{"id":10602,"date":"2022-06-03T14:57:09","date_gmt":"2022-06-03T12:57:09","guid":{"rendered":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/garmisch-partenkirchen-zug-unglueck-entgleist-augenzeuge-bericht-tote-verletzte-grund-herrmann-soeder-polizei-91590578-html-10602\/"},"modified":"2022-06-03T14:57:09","modified_gmt":"2022-06-03T12:57:09","slug":"garmisch-partenkirchen-zug-unglueck-entgleist-augenzeuge-bericht-tote-verletzte-grund-herrmann-soeder-polizei-91590578-html","status":"publish","type":"post","link":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/garmisch-partenkirchen-zug-unglueck-entgleist-augenzeuge-bericht-tote-verletzte-grund-herrmann-soeder-polizei-91590578-html-10602\/","title":{"rendered":"Augenzeuge \u00fcber Zugungl\u00fcck in Garmisch-Partenkirchen:  \u201eEinfach schrecklich, pl\u00f6tzlich ist der Zug umgekippt\u201c"},"content":{"rendered":"<div>Trag\u00f6die in Oberbayern: Nahe Garmisch-Partenkirchen ist der Teil eines Zuges entgleist, es gibt Tote und Verletzte. Ein Augenzeuge schildert den Moment.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Trag\u00f6die in Oberbayern: Nahe Garmisch-Partenkirchen ist der Teil eines Zuges entgleist, es gibt Tote und Verletzte. Ein Augenzeuge schildert den Moment.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/10602"}],"collection":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/comments?post=10602"}],"version-history":[{"count":0,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/10602\/revisions"}],"wp:attachment":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/media?parent=10602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/categories?post=10602"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/tags?post=10602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}