{"id":11772,"date":"2022-07-25T11:00:00","date_gmt":"2022-07-25T09:00:00","guid":{"rendered":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/aemteruebergabe-des-lions-clubs-garmisch-partenkirchen-91686223-html-3-11772\/"},"modified":"2022-07-25T11:00:00","modified_gmt":"2022-07-25T09:00:00","slug":"aemteruebergabe-des-lions-clubs-garmisch-partenkirchen-91686223-html-3","status":"publish","type":"post","link":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/aemteruebergabe-des-lions-clubs-garmisch-partenkirchen-91686223-html-3-11772\/","title":{"rendered":"\u00c4mter\u00fcbergabe des Lions Clubs Garmisch-Partenkirchen"},"content":{"rendered":"<div>GAP \u2013 Unter Anwesenheit eines Gro\u00dfteils der Mitglieder fand im Riessersee Seehaus die \u00c4mter\u00fcbergabe des Lions Clubs Garmisch-Partenkirchen statt. Dabei \u00fcbergab Pr\u00e4sident Mario Springer die Pr\u00e4sidentennadel an seinen Nachfolger Dr. Tobias May. Davor lie\u00df Mario Springer sein Lionsjahr, das gepr\u00e4gt war durch die Pandemie und die damit verbundenen starken Einschr\u00e4nkungen, noch einmal Revue passieren und bedankte sich bei seinem Team. Der neue Pr\u00e4sident Dr. Tobias May stellte sein Lionsjahr unter das Motto \u201eMit der Kraft Aller die Gemeinschaft st\u00e4rken\u201c.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>GAP \u2013 Unter Anwesenheit eines Gro\u00dfteils der Mitglieder fand im Riessersee Seehaus die \u00c4mter\u00fcbergabe des Lions Clubs Garmisch-Partenkirchen statt. Dabei \u00fcbergab Pr\u00e4sident Mario Springer die Pr\u00e4sidentennadel an seinen Nachfolger Dr. Tobias May. Davor lie\u00df Mario Springer sein Lionsjahr, das gepr\u00e4gt war durch die Pandemie und die damit verbundenen starken Einschr\u00e4nkungen, noch einmal Revue passieren und bedankte sich bei seinem Team.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/11772"}],"collection":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/comments?post=11772"}],"version-history":[{"count":0,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/11772\/revisions"}],"wp:attachment":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/media?parent=11772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/categories?post=11772"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/tags?post=11772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}