{"id":16099,"date":"2024-02-06T09:43:45","date_gmt":"2024-02-06T08:43:45","guid":{"rendered":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/winnetou-und-seine-werdenfelser-heimat-hier-die-gluecklichsten-menschen-92816741-html-16099\/"},"modified":"2024-02-06T09:43:45","modified_gmt":"2024-02-06T08:43:45","slug":"winnetou-und-seine-werdenfelser-heimat-hier-die-gluecklichsten-menschen-92816741-html","status":"publish","type":"post","link":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/winnetou-und-seine-werdenfelser-heimat-hier-die-gluecklichsten-menschen-92816741-html-16099\/","title":{"rendered":"Winnetou und seine Werdenfelser Heimat: \u201eHier waren wir die gl\u00fccklichsten Menschen\u201c"},"content":{"rendered":"<div>Garmisch-Partenkirchen war f\u00fcr Pierre und Hella Brice immer ein Zuhause. Viele wunderbare Urlaube haben der Schauspieler und seine Frau hier verbracht. Zum 95. Geburtstag ihres verstorbenen Mannes erinnert sie sich an gl\u00fcckliche Zeiten und freut sich auf die Vorstellung im Kleinen Theater.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Garmisch-Partenkirchen war f\u00fcr Pierre und Hella Brice immer ein Zuhause. Viele wunderbare Urlaube haben der Schauspieler und seine Frau hier verbracht. Zum 95. Geburtstag ihres verstorbenen Mannes erinnert sie sich an gl\u00fcckliche Zeiten und freut sich auf die Vorstellung im Kleinen Theater.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/16099"}],"collection":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/comments?post=16099"}],"version-history":[{"count":0,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/16099\/revisions"}],"wp:attachment":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/media?parent=16099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/categories?post=16099"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/tags?post=16099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}