{"id":18107,"date":"2024-06-12T09:12:00","date_gmt":"2024-06-12T07:12:00","guid":{"rendered":"http:\/\/cms.mtsomnii.de\/w7\/kreisbote-gap\/das-herz-von-garmisch-partenkirchen-marktarchiv-leidet-unter-platznot-und-raumklima-93124761-html-18107\/"},"modified":"2024-06-12T09:12:00","modified_gmt":"2024-06-12T07:12:00","slug":"das-herz-von-garmisch-partenkirchen-marktarchiv-leidet-unter-platznot-und-raumklima-93124761-html","status":"publish","type":"post","link":"http:\/\/cms.mtsomnii.de\/w7\/kreisbote-gap\/das-herz-von-garmisch-partenkirchen-marktarchiv-leidet-unter-platznot-und-raumklima-93124761-html-18107\/","title":{"rendered":"Das Herz von Garmisch-Partenkirchen: Marktarchiv leidet unter Platznot und Raumklima"},"content":{"rendered":"<div>Der Sachstandbericht von Marktarchivar Leonhard Herr im Marktgemeinderat zeigt deutlich: Im Archiv gibt es dringenden Handlungsbedarf. Die Verwaltung ist nun beauftragt, m\u00f6gliche L\u00f6sungen zur Verbesserung der r\u00e4umlichen und technisch-organisatorischen Situation zu erarbeiten.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Sachstandbericht von Marktarchivar Leonhard Herr im Marktgemeinderat zeigt deutlich: Im Archiv gibt es dringenden Handlungsbedarf. Die Verwaltung ist nun beauftragt, m\u00f6gliche L\u00f6sungen zur Verbesserung der r\u00e4umlichen und technisch-organisatorischen Situation zu erarbeiten.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/18107"}],"collection":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/comments?post=18107"}],"version-history":[{"count":0,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/18107\/revisions"}],"wp:attachment":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/media?parent=18107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/categories?post=18107"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/tags?post=18107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}