{"id":21283,"date":"2025-07-13T16:00:00","date_gmt":"2025-07-13T14:00:00","guid":{"rendered":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/kunst-fuers-volk-aus-glas-gemacht-glaeubige-in-wallfahrtsorten-kauften-hunderttausende-heiligenbilder-93827167-html-3-21283\/"},"modified":"2025-07-13T16:00:00","modified_gmt":"2025-07-13T14:00:00","slug":"kunst-fuers-volk-aus-glas-gemacht-glaeubige-in-wallfahrtsorten-kauften-hunderttausende-heiligenbilder-93827167-html-3","status":"publish","type":"post","link":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/kunst-fuers-volk-aus-glas-gemacht-glaeubige-in-wallfahrtsorten-kauften-hunderttausende-heiligenbilder-93827167-html-3-21283\/","title":{"rendered":"Gl\u00e4ubige in Wallfahrtsorten kauften hunderttausende Heiligenbilder"},"content":{"rendered":"<div>Zwischen 1750 und dem Ende des 19. Jahrhunderts waren in Oberammergau die Hinterglasmaler zu Hause. Gerade nach der S\u00e4kularisation bl\u00fchte dieses Kunsthandwerk. Damals verkauften die Passionsd\u00f6rfler bunte Heiligenmotive zu 100000er-St\u00fcckzahlen an die Gl\u00e4ubigen in den europ\u00e4ischen Wallfahrtsorten.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Zwischen 1750 und dem Ende des 19. Jahrhunderts waren in Oberammergau die Hinterglasmaler zu Hause. Gerade nach der S\u00e4kularisation bl\u00fchte dieses Kunsthandwerk. Damals verkauften die Passionsd\u00f6rfler bunte Heiligenmotive zu 100000er-St\u00fcckzahlen an die Gl\u00e4ubigen in den europ\u00e4ischen Wallfahrtsorten.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/21283"}],"collection":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/comments?post=21283"}],"version-history":[{"count":0,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/21283\/revisions"}],"wp:attachment":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/media?parent=21283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/categories?post=21283"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/tags?post=21283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}