{"id":21709,"date":"2025-09-04T08:00:00","date_gmt":"2025-09-04T06:00:00","guid":{"rendered":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/da-oimsumma-is-umma-auch-im-isartal-93914669-html-2-21709\/"},"modified":"2025-09-04T08:00:00","modified_gmt":"2025-09-04T06:00:00","slug":"da-oimsumma-is-umma-auch-im-isartal-93914669-html-2","status":"publish","type":"post","link":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/da-oimsumma-is-umma-auch-im-isartal-93914669-html-2-21709\/","title":{"rendered":"\u201eDa Oimsumma is umma\u201c &#8211; auch im Isartal"},"content":{"rendered":"<div>Wenn im Herbst die Tiere von den saftigen Bergwiesen zur\u00fcck ins Tal ziehen, wird im Isartal ein jahrhundertealtes Ritual lebendig. Der Almabtrieb ist weit mehr als ein schlichter Viehtrieb. Er markiert den feierlichen Abschluss des Almsommers und bringt Mensch und Tier wieder in die N\u00e4he der D\u00f6rfer, wo die Tiere die  Wintermonate in den sch\u00fctzenden St\u00e4llen verbringen.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wenn im Herbst die Tiere von den saftigen Bergwiesen zur\u00fcck ins Tal ziehen, wird im Isartal ein jahrhundertealtes Ritual lebendig. Der Almabtrieb ist weit mehr als ein schlichter Viehtrieb. Er markiert den feierlichen Abschluss des Almsommers und bringt Mensch und Tier wieder in die N\u00e4he der D\u00f6rfer, wo die Tiere die Wintermonate in den sch\u00fctzenden St\u00e4llen verbringen.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/21709"}],"collection":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/comments?post=21709"}],"version-history":[{"count":0,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/21709\/revisions"}],"wp:attachment":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/media?parent=21709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/categories?post=21709"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/tags?post=21709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}