{"id":21770,"date":"2025-09-11T11:00:00","date_gmt":"2025-09-11T09:00:00","guid":{"rendered":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/500-000-euro-fuer-den-ettaler-berg-93928369-html-21770\/"},"modified":"2025-09-11T11:00:00","modified_gmt":"2025-09-11T09:00:00","slug":"500-000-euro-fuer-den-ettaler-berg-93928369-html","status":"publish","type":"post","link":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/500-000-euro-fuer-den-ettaler-berg-93928369-html-21770\/","title":{"rendered":"500.000 Euro f\u00fcr die Sicherheit: \u201eDringende\u201c Arbeiten am Ettaler Berg"},"content":{"rendered":"<div>Zwei Wochen lang geh\u00f6rte der Ettaler Berg allein den Bauarbeitern und ihren schweren Maschinen. Unter anderem errichteten sie eine neue St\u00fctzmauer, brachten eine neue Teerdecke auf und fixierten Stahlnetze an der Felswand. Nach der Vollsperrung wird die Strecke am Freitag um 18 Uhr wieder f\u00fcr den Verkehr freigegeben.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Zwei Wochen lang geh\u00f6rte der Ettaler Berg allein den Bauarbeitern und ihren schweren Maschinen. Unter anderem errichteten sie eine neue St\u00fctzmauer, brachten eine neue Teerdecke auf und fixierten Stahlnetze an der Felswand. Nach der Vollsperrung wird die Strecke am Freitag um 18 Uhr wieder f\u00fcr den Verkehr freigegeben.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/21770"}],"collection":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/comments?post=21770"}],"version-history":[{"count":0,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/21770\/revisions"}],"wp:attachment":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/media?parent=21770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/categories?post=21770"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/tags?post=21770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}