{"id":3792,"date":"2020-10-06T08:54:00","date_gmt":"2020-10-06T08:54:00","guid":{"rendered":"https:\/\/w7vongap.de\/merkur-de-gap\/mittenwald-foehnsturm-garmisch-partenkirchen-baum-faellt-autodach-feuerwehr-einsatz-90061641-html-3747\/"},"modified":"2020-10-06T08:54:00","modified_gmt":"2020-10-06T08:54:00","slug":"mittenwald-foehnsturm-garmisch-partenkirchen-baum-faellt-autodach-feuerwehr-einsatz-90061641-html","status":"publish","type":"post","link":"http:\/\/cms.mtsomnii.de\/w7\/merkur-de-gap\/mittenwald-foehnsturm-garmisch-partenkirchen-baum-faellt-autodach-feuerwehr-einsatz-90061641-html-3792\/","title":{"rendered":"F\u00f6hnsturm w\u00fctet: B\u00e4ume fallen reihenweise &#8211; einer trifft fahrendes Auto mit voller Wucht"},"content":{"rendered":"<div>Ein F&ouml;hnsturm hat Wochenende im Landkreis Garmisch-Partenkirchen gew&uuml;tet. F&uuml;r eine Autofahrerin endete dies beinahe mit einer Trag&ouml;die.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ein F&ouml;hnsturm hat Wochenende im Landkreis Garmisch-Partenkirchen gew&uuml;tet. F&uuml;r eine Autofahrerin endete dies beinahe mit einer Trag&ouml;die.<\/p>\n","protected":false},"author":5,"featured_media":228,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/3792"}],"collection":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/comments?post=3792"}],"version-history":[{"count":0,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/posts\/3792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/media\/228"}],"wp:attachment":[{"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/media?parent=3792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/categories?post=3792"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cms.mtsomnii.de\/w7\/wp-json\/wp\/v2\/tags?post=3792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}